{"id":763,"date":"2013-06-03T18:48:00","date_gmt":"2013-06-03T16:48:00","guid":{"rendered":"http:\/\/www.norbert-martsch.de\/index.php\/2013\/06\/03\/norbert-martsch-neues-anzeigemodul-fur\/"},"modified":"2017-05-18T11:03:35","modified_gmt":"2017-05-18T09:03:35","slug":"norbert-martsch-neues-anzeigemodul-fur","status":"publish","type":"post","link":"https:\/\/www.schnorpstronik.de\/index.php\/2013\/06\/03\/norbert-martsch-neues-anzeigemodul-fur\/","title":{"rendered":"Norbert Martsch: Neues Anzeigemodul f\u00fcr bis zu 32 Verbraucher: AZM-16-32-V1"},"content":{"rendered":"<p>Ein neues Anzeigemodul f\u00fcr Selectrix ist als Bausatz verf\u00fcgbar. Das AZM-16-32-V1 genannte Modul kann bis zu 32 Einzelausg\u00e4nge schalten, alternativ 2x 16 alternierend (hin-und-her).<br \/>\nIm Modus der 32 Einzelausg\u00e4nge k\u00f6nnen diese als Dauer-, Blink- oder Impulsausgang konfiguriert werden &#8211; jeder Ausgang individuell f\u00fcr sich. Blink- und Impulsdauer sind elektronisch via SX-Bus programmierbar, ebenso wie alle anderen Parameter auch (SX-Adressen, Modus, &#8230;). Als Besonderheit ist noch eine Lauflicht-Option integriert. Mit dieser kann eine vorbildgetreue Baustellen-Absperrung beleuchtet werden &#8211; daf\u00fcr stehen 8 Ausg\u00e4nge f\u00fcr das Lauflicht zur Verf\u00fcgung. <br \/>\nIm Modus der 16 alternierenden Ausg\u00e4nge k\u00f6nnen Weichenlagen\/Weichenr\u00fcckmeldungen dargestellt werden &#8211; es wird je nach Weichenlage zwischen 2 Ausg\u00e4ngen hin und her geschaltet.<br \/>\nF\u00fcr die Verbraucher stehen insg. 3,1A zur Verf\u00fcgung, das macht rechnerisch ~100mA pro Ausgang &#8211; dies reicht sogar f\u00fcr 5 Standard-LEDs in Reihe pro Ausgang (nat\u00fcrlich k\u00f6nnen auch LEDs einzeln angeschlossen werden), Modellbahngl\u00fchlampen und sogar Relais. Zu versorgen ist das Modul mit 10&#8230;18V AC oder 14&#8230;22V DC.<br \/>\nDer SX-Bus kann entweder mittels Standard-SX-Kabel (5-polig, DIN) heran- und weitergef\u00fchrt werden, alternativ steht ein 10-poliger Flachbandkabel-Anschluss nach D&amp;H-Norm zur Verf\u00fcgung. <\/p>\n<p>Mehr Infos unter:<\/p>\n<ul>\n<li>https:\/\/www.schnorpstronik.de\/index.php\/selectrix-elektronik\/anzeigemodul-v1\/<br \/>und<\/li>\n<li>http:\/\/norbert-martsch.blogspot.de\/2013\/05\/azm-16-32-v1-neues-1632-fach.html<\/li>\n<\/ul>\n<table align=\"center\" cellpadding=\"0\" cellspacing=\"0\" class=\"tr-caption-container\" style=\"margin-left: auto; margin-right: auto; text-align: center;\">\n<tbody>\n<tr>\n<td style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"274\" src=\"https:\/\/www.schnorpstronik.de\/wp-content\/uploads\/2013\/06\/azm-16-32-v0_8_2-prototyp_bestueckt.jpg\" style=\"margin-left: auto; margin-right: auto;\" width=\"320\" \/><\/td>\n<\/tr>\n<tr>\n<td class=\"tr-caption\" style=\"text-align: center;\">AZM-8-16-V0.8.2 &#8211; Prototyp best\u00fcckt<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div class=\"separator\" style=\"clear: both; text-align: center;\">\n<\/div>\n<div class=\"separator\" style=\"clear: both; text-align: center;\">\n<\/div>\n<p><\/p>\n<table align=\"center\" cellpadding=\"0\" cellspacing=\"0\" class=\"tr-caption-container\" style=\"margin-left: auto; margin-right: auto; text-align: center;\">\n<tbody>\n<tr>\n<td style=\"text-align: center;\"><a href=\"http:\/\/1.bp.blogspot.com\/-AU2BTnIEV5Y\/UazkeLhmdHI\/AAAAAAAACv8\/etEgt4bo1KY\/s1600\/azm-16-32-v1_0_0-pcb_bottom_top.jpg\" imageanchor=\"1\" style=\"margin-left: auto; margin-right: auto;\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"178\" src=\"https:\/\/www.schnorpstronik.de\/wp-content\/uploads\/2013\/06\/azm-16-32-v1_0_0-pcb_bottom_top.jpg\" width=\"320\" \/><\/a><\/td>\n<\/tr>\n<tr>\n<td class=\"tr-caption\" style=\"text-align: center;\">AZM-8-16-V1.0.0 &#8211; Platinen<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Ein neues Anzeigemodul f\u00fcr Selectrix ist als Bausatz verf\u00fcgbar. Das AZM-16-32-V1 genannte Modul kann bis zu 32 Einzelausg\u00e4nge schalten, alternativ 2x 16 alternierend (hin-und-her). Im Modus der 32 Einzelausg\u00e4nge k\u00f6nnen diese als Dauer-, Blink- oder Impulsausgang konfiguriert werden &#8211; jeder &hellip; <a href=\"https:\/\/www.schnorpstronik.de\/index.php\/2013\/06\/03\/norbert-martsch-neues-anzeigemodul-fur\/\">Weiter<\/a><\/p>\n","protected":false},"author":1,"featured_media":856,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[29],"tags":[25],"class_list":["post-763","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sx-news-blog","tag-norbert-martsch"],"_links":{"self":[{"href":"https:\/\/www.schnorpstronik.de\/index.php\/wp-json\/wp\/v2\/posts\/763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.schnorpstronik.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schnorpstronik.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schnorpstronik.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schnorpstronik.de\/index.php\/wp-json\/wp\/v2\/comments?post=763"}],"version-history":[{"count":0,"href":"https:\/\/www.schnorpstronik.de\/index.php\/wp-json\/wp\/v2\/posts\/763\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schnorpstronik.de\/index.php\/wp-json\/wp\/v2\/media\/856"}],"wp:attachment":[{"href":"https:\/\/www.schnorpstronik.de\/index.php\/wp-json\/wp\/v2\/media?parent=763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schnorpstronik.de\/index.php\/wp-json\/wp\/v2\/categories?post=763"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schnorpstronik.de\/index.php\/wp-json\/wp\/v2\/tags?post=763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}